{"id":66256,"date":"2026-05-12T16:17:41","date_gmt":"2026-05-12T23:17:41","guid":{"rendered":"https:\/\/www.puntociegoeditorial.com\/web\/?p=66256"},"modified":"2026-05-12T16:17:41","modified_gmt":"2026-05-12T23:17:41","slug":"semujeres-e-icatsin-impulsan-taller-de-liderazgo-femenino-para-colaboradoras-y-asi-potenciar-nuevas-capacidades","status":"publish","type":"post","link":"https:\/\/www.puntociegoeditorial.com\/web\/2026\/05\/12\/semujeres-e-icatsin-impulsan-taller-de-liderazgo-femenino-para-colaboradoras-y-asi-potenciar-nuevas-capacidades\/","title":{"rendered":"SEMUJERES e ICATSIN impulsan taller de liderazgo femenino para colaboradoras y as\u00ed potenciar nuevas capacidades"},"content":{"rendered":"\n<p>Culiac\u00e1n, Sinaloa, 12 de mayo de 2026. Con el objetivo de fortalecer las habilidades de liderazgo, comunicaci\u00f3n y toma de decisiones de las colaboradoras de la Secretar\u00eda de las Mujeres de Sinaloa, este martes dio inicio el taller: \u201cLiderazgo Femenino\u201d, realizado en coordinaci\u00f3n entre el ICATSIN y la Secretar\u00eda de las Mujeres de Sinaloa.<\/p>\n\n\n\n<p>La capacitaci\u00f3n, busca promover el desarrollo profesional de las participantes y fortalecer su capacidad de incidencia en sus espacios de trabajo, mediante herramientas orientadas al liderazgo con perspectiva de g\u00e9nero.<\/p>\n\n\n\n<p>Como parte del mensaje de la Mtra. Brenda Roc\u00edo Garc\u00eda F\u00e9lix, Directora de ICATSIN, destac\u00f3 la importancia de generar espacios de formaci\u00f3n que impulsen el crecimiento profesional de otras mujeres y seguir trabajando coordinadamente.<\/p>\n\n\n\n<p>\u201cEn colaboraci\u00f3n con la Secretar\u00eda de las Mujeres, pues siempre vamos a estar buscando e impulsando este tipo de trabajos para poder nosotros como mujeres quitar estigmas, poder llegar a muchas m\u00e1s mujeres y que conozcan sus derechos a hacer valer sus derechos que tambi\u00e9n es muy importante y pues continuamos en esta buena colaboraci\u00f3n. Hemos tenido muy buena relaci\u00f3n\u201d, indic\u00f3 la directora de ICATSIN.<\/p>\n\n\n\n<p>Posteriormente, la Subsecretaria de Igualdad Sustantiva y Perspectiva de G\u00e9nero, Lcda. Rosa Elena Mill\u00e1n Bueno, emiti\u00f3 el mensaje inaugural en representaci\u00f3n de la Secretaria de las Mujeres, Lcda. Ana Francis Chiquete Elizalde, resaltando la relevancia de fortalecer liderazgos de las mujeres comprometidos con la transformaci\u00f3n institucional y la igualdad sustantiva.<\/p>\n\n\n\n<p>\u201cEntonces yo creo que mucho el objetivo de este curso va encaminado precisamente a fortalecer esa capacidad que tenemos todas, todos y todes de la atenci\u00f3n que le damos a las personas, a la ciudadan\u00eda, pero qu\u00e9 creen eso lleva un extra porque todo ese conocimiento no lo llevamos a la casa y ah\u00ed hacemos de nuestras hijas, de nuestros hijos, del esposo, de la esposa, de los padres, las madres, los vecinos, en fin, el c\u00edrculo de inter\u00e9s en donde nos movemos ah\u00ed estamos tambi\u00e9n un c\u00edrculo emp\u00e1tico donde el conocimiento nuestro y el ejemplo se traduce precisamente a multiplicar y esperar el conocimiento que aqu\u00ed vamos a tener. Por eso nos da mucho gusto empezar esta jornada de sensibilizaci\u00f3n y capacitaci\u00f3n\u201d, expres\u00f3 la Lcda. Rosa Elena Mill\u00e1n Bueno.<\/p>\n\n\n\n<p>Estuvieron presentes la Subsecretaria de Acceso de las Mujeres a una Vida Libre de Violencia, Mtra. Egle\u00e9 Hern\u00e1ndez Grijalva; la tallerista Lcda. Cristina Bastinas; as\u00ed como la directora del plantel Culiac\u00e1n 4 CECADET, Lcda. Ana\u00eds Lorena Valle Sandoval.<\/p>\n\n\n\n<p>Este taller tiene duraci\u00f3n de dos d\u00edas a partir de las 11 de la ma\u00f1ana a 4 de la tarde, una herramienta clave para construir espacios laborales m\u00e1s igualitarios, con liderazgos fuertes y con perspectiva de g\u00e9nero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Culiac\u00e1n, Sinaloa, 12 de mayo de 2026. Con el objetivo de fortalecer las habilidades de liderazgo, comunicaci\u00f3n y toma de decisiones de las colaboradoras de la Secretar\u00eda de las Mujeres de Sinaloa, este martes dio inicio el taller: \u201cLiderazgo Femenino\u201d, realizado en coordinaci\u00f3n entre el ICATSIN y la Secretar\u00eda de las Mujeres de Sinaloa. La [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":66257,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_mi_skip_tracking":false,"footnotes":""},"categories":[13],"tags":[],"class_list":["post-66256","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sinaloa"],"_links":{"self":[{"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/posts\/66256","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/comments?post=66256"}],"version-history":[{"count":1,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/posts\/66256\/revisions"}],"predecessor-version":[{"id":66258,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/posts\/66256\/revisions\/66258"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/media\/66257"}],"wp:attachment":[{"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/media?parent=66256"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/categories?post=66256"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.puntociegoeditorial.com\/web\/wp-json\/wp\/v2\/tags?post=66256"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}